{"id":36758,"date":"2026-07-14T17:13:00","date_gmt":"2026-07-14T20:13:00","guid":{"rendered":"https:\/\/catamarcadespierta.com.ar\/nota\/13787"},"modified":"2026-07-14T17:13:00","modified_gmt":"2026-07-14T20:13:00","slug":"la-ciudad-volvio-a-quedar-impecable-tras-los-festejos","status":"publish","type":"post","link":"https:\/\/nvccatamarca.com\/index.php\/2026\/07\/14\/la-ciudad-volvio-a-quedar-impecable-tras-los-festejos\/","title":{"rendered":"LA CIUDAD VOLVI\u00d3 A QUEDAR IMPECABLE TRAS LOS FESTEJOS"},"content":{"rendered":"<p><img decoding=\"async\" alt=\"\ud83c\udde6\ud83c\uddf7\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t48\/1\/16\/1f1e6_1f1f7.png\"> Luego de la multitudinaria celebraci\u00f3n por una nueva victoria de la Selecci\u00f3n Argentina, comenz\u00f3 una tarea igual de importante.<\/p>\n<p><img decoding=\"async\" alt=\"\ud83d\ude9b\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t97\/1\/16\/1f69b.png\"> El equipo de Higiene Urbana despleg\u00f3 un intenso operativo de limpieza en la Plaza 25 de Mayo y en las calles aleda\u00f1as, dejando en \u00f3ptimas condiciones los espacios p\u00fablicos para que todos los vecinos puedan seguir disfrut\u00e1ndolos.<\/p>\n<p><img decoding=\"async\" alt=\"\ud83d\udc4f\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tfe\/1\/16\/1f44f.png\"> Un reconocimiento para quienes, mientras la ciudad celebraba, trabajaron para que Catamarca amaneciera limpia y ordenada<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de la multitudinaria celebraci\u00f3n por una nueva victoria de la Selecci\u00f3n Argentina, comenz\u00f3 una tarea igual de importante. El equipo de Higiene Urbana despleg\u00f3 un intenso operativo de limpieza en la Plaza 25 de Mayo y en las calles aleda\u00f1as, dejando en \u00f3ptimas condiciones los espacios p\u00fablicos para que todos los vecinos puedan seguir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132],"tags":[],"class_list":["post-36758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados"],"_links":{"self":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts\/36758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/comments?post=36758"}],"version-history":[{"count":0,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts\/36758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/media\/36759"}],"wp:attachment":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/media?parent=36758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/categories?post=36758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/tags?post=36758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}