{"id":36774,"date":"2026-07-14T17:21:03","date_gmt":"2026-07-14T20:21:03","guid":{"rendered":"https:\/\/airevision.com.ar\/?p=184371"},"modified":"2026-07-14T17:21:03","modified_gmt":"2026-07-14T20:21:03","slug":"provincias-del-norte-grande-exigen-a-nacion-financiamiento-y-crean-mesa-federal-para-salvar-incluir-salud","status":"publish","type":"post","link":"https:\/\/nvccatamarca.com\/index.php\/2026\/07\/14\/provincias-del-norte-grande-exigen-a-nacion-financiamiento-y-crean-mesa-federal-para-salvar-incluir-salud\/","title":{"rendered":"Provincias del Norte Grande exigen a Naci\u00f3n financiamiento y crean mesa federal para salvar Incluir Salud"},"content":{"rendered":"<div class=\"td-post-featured-image\"><a href=\"https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6.jpeg\" data-caption><img loading=\"lazy\" decoding=\"async\" data-lazyloaded=\"1\" src=\"https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6-696x464.jpeg\" width=\"696\" height=\"464\" class=\"entry-thumb td-modal-image\" data-sizes=\"(max-width: 696px) 100vw, 696px\" alt title=\"89efe30e-b49d-4aa7-a8b2-8202b46cb1a6\" srcset=\"https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6-696x464.jpeg 696w, https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6-300x200.jpeg 300w, https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6-1024x683.jpeg 1024w, https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6-768x512.jpeg 768w, https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6-150x100.jpeg 150w, https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6-1068x712.jpeg 1068w, https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/89efe30e-b49d-4aa7-a8b2-8202b46cb1a6.jpeg 1500w\"><\/a><\/div>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:align-top\">La ministra de Salud de Catamarca, Johana Carrizo, particip\u00f3 en Santiago del Estero de un encuentro de ministros del Norte Grande junto a referentes del Programa Incluir Salud. El objetivo fue evaluar la situaci\u00f3n del programa y coordinar acciones frente al desfinanciamiento por parte del Gobierno nacional.<\/p>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:align-top\">Las autoridades provinciales se\u00f1alaron que la falta de fondos puso al programa en una situaci\u00f3n cr\u00edtica y generalizada en la regi\u00f3n. Ante ello, las provincias vienen destinando recursos propios para evitar la interrupci\u00f3n de tratamientos, sostener la provisi\u00f3n de medicamentos, garantizar prestaciones de di\u00e1lisis y cubrir traslados, adem\u00e1s de atender urgencias cl\u00ednicas.<\/p>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:align-top\">En la reuni\u00f3n se consensu\u00f3 un documento conjunto y se acord\u00f3 la creaci\u00f3n de una mesa federal permanente para el seguimiento del Programa Incluir Salud, con representaci\u00f3n de la Naci\u00f3n y de las provincias. La iniciativa ser\u00e1 presentada ante el Ministerio de Salud de la Naci\u00f3n en la pr\u00f3xima reuni\u00f3n del Consejo Federal de Salud (COFESA), con la intenci\u00f3n de impulsar respuestas concretas y establecer una agenda que garantice la continuidad, equidad y calidad de las prestaciones.<\/p>\n<p class=\"my-2 [&amp;+p]:mt-4 [&amp;_strong:has(+br)]:inline-block [&amp;_strong:has(+br)]:align-top\">Las provincias del Norte Grande reafirmaron el compromiso de trabajar de forma articulada para promover una respuesta federal y exigir soluciones urgentes, previsibles y sostenibles para el financiamiento del programa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ministra de Salud de Catamarca, Johana Carrizo, particip\u00f3 en Santiago del Estero de un encuentro de ministros del Norte Grande junto a referentes del Programa Incluir Salud. El objetivo fue evaluar la situaci\u00f3n del programa y coordinar acciones frente al desfinanciamiento por parte del Gobierno nacional. Las autoridades provinciales se\u00f1alaron que la falta de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36775,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132],"tags":[],"class_list":["post-36774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados"],"_links":{"self":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts\/36774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/comments?post=36774"}],"version-history":[{"count":0,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts\/36774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/media\/36775"}],"wp:attachment":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/media?parent=36774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/categories?post=36774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/tags?post=36774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}