{"id":36776,"date":"2026-07-14T11:59:31","date_gmt":"2026-07-14T14:59:31","guid":{"rendered":"https:\/\/airevision.com.ar\/?p=184368"},"modified":"2026-07-14T11:59:31","modified_gmt":"2026-07-14T14:59:31","slug":"la-caja-de-credito-municipal-otorgo-cerca-de-200-creditos-para-emprendedores-de-la-fiesta-del-poncho","status":"publish","type":"post","link":"https:\/\/nvccatamarca.com\/index.php\/2026\/07\/14\/la-caja-de-credito-municipal-otorgo-cerca-de-200-creditos-para-emprendedores-de-la-fiesta-del-poncho\/","title":{"rendered":"La Caja de Cr\u00e9dito Municipal otorg\u00f3 cerca de 200 cr\u00e9ditos para emprendedores de la Fiesta del Poncho"},"content":{"rendered":"<div><img decoding=\"async\" src=\"https:\/\/airevision.com.ar\/wp-content\/uploads\/2026\/07\/WhatsApp-Image-2026-07-14-at-11.46.48.jpeg\" class=\"ff-og-image-inserted\"><\/div>\n<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"106\" data-end=\"389\">El presidente de la Caja de Cr\u00e9dito Municipal, <strong data-start=\"153\" data-end=\"171\">Juan Zelaray\u00e1n<\/strong>, destac\u00f3 el acompa\u00f1amiento financiero que la instituci\u00f3n brinda a artesanos, productores y dise\u00f1adores que participan de la Fiesta Nacional e Internacional del Poncho, a trav\u00e9s de la l\u00ednea de cr\u00e9ditos <strong data-start=\"373\" data-end=\"388\">Poncho 2026<\/strong>.<\/p>\n<p data-start=\"391\" data-end=\"769\">El programa fue lanzado en mayo y, hasta la fecha, permiti\u00f3 otorgar alrededor de <strong data-start=\"472\" data-end=\"488\">200 cr\u00e9ditos<\/strong> de <strong data-start=\"492\" data-end=\"517\">1,5 millones de pesos<\/strong> cada uno, lo que representa una asistencia cercana a los <strong data-start=\"575\" data-end=\"600\">150 millones de pesos<\/strong>. Los pr\u00e9stamos cuentan con una <strong data-start=\"632\" data-end=\"670\">tasa preferencial del 1,5% mensual<\/strong>, sin costos financieros ni administrativos adicionales, y pueden devolverse en hasta <strong data-start=\"756\" data-end=\"768\">12 meses<\/strong>.<\/p>\n<p data-start=\"771\" data-end=\"990\">Zelaray\u00e1n se\u00f1al\u00f3 que los beneficiarios utilizaron principalmente los fondos para la compra de insumos y el pago de los espacios de exposici\u00f3n dentro de la feria, lo que permiti\u00f3 fortalecer su participaci\u00f3n en el evento.<\/p>\n<p data-start=\"992\" data-end=\"1213\">Adem\u00e1s, remarc\u00f3 que, si bien la prioridad de la Caja son los emprendedores de la capital, este a\u00f1o tambi\u00e9n se atendieron solicitudes de productores del interior provincial, entre ellos artesanos y bodegueros de Tinogasta.<\/p>\n<p data-start=\"1215\" data-end=\"1517\" data-is-last-node data-is-only-node>Finalmente, adelant\u00f3 que, una vez concluida la Fiesta del Poncho, se realizar\u00e1 un balance del programa, mientras que la entidad continuar\u00e1 con sus l\u00edneas habituales de cr\u00e9ditos personales para empleados municipales y luego avanzar\u00e1 con la tradicional l\u00ednea de financiamiento para turismo de fin de a\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Caja de Cr\u00e9dito Municipal, Juan Zelaray\u00e1n, destac\u00f3 el acompa\u00f1amiento financiero que la instituci\u00f3n brinda a artesanos, productores y dise\u00f1adores que participan de la Fiesta Nacional e Internacional del Poncho, a trav\u00e9s de la l\u00ednea de cr\u00e9ditos Poncho 2026. El programa fue lanzado en mayo y, hasta la fecha, permiti\u00f3 otorgar alrededor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[132],"tags":[],"class_list":["post-36776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados"],"_links":{"self":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts\/36776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/comments?post=36776"}],"version-history":[{"count":0,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/posts\/36776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/media\/36777"}],"wp:attachment":[{"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/media?parent=36776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/categories?post=36776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvccatamarca.com\/index.php\/wp-json\/wp\/v2\/tags?post=36776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}